{"id":5416,"date":"2023-01-19T10:00:00","date_gmt":"2023-01-19T09:00:00","guid":{"rendered":"https:\/\/www.bikai.eu\/politica-de-privacidad\/"},"modified":"2023-02-06T23:40:29","modified_gmt":"2023-02-06T22:40:29","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Privacy Policy<\/h1>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Protecci\u00f3n de datos de car\u00e1cter personal seg\u00fan la LOPD<\/strong><\/p>\n\n\n\n<p>Bikai S.L., en aplicaci\u00f3n de la normativa vigente en materia de protecci\u00f3n de datos de car\u00e1cter personal, informa que los datos personales que se recogen a trav\u00e9s de los formularios del Sitio web: bikai.eu, se incluyen en los ficheros automatizados espec\u00edficos de usuarios de los servicios de Bikai S.L.<\/p>\n\n\n\n<p>La recogida y tratamiento automatizado de los datos de car\u00e1cter personal tiene como finalidad el mantenimiento de la relaci\u00f3n comercial y el desempe\u00f1o de tareas de informaci\u00f3n, formaci\u00f3n, asesoramiento y otras actividades propias de Bikai S.L.<\/p>\n\n\n\n<p>Estos datos \u00fanicamente ser\u00e1n cedidos a aquellas entidades que sean necesarias con el \u00fanico objetivo de dar cumplimiento a la finalidad anteriormente expuesta.<\/p>\n\n\n\n<p>Bikai S.L. adopta las medidas necesarias para garantizar la seguridad, integridad y confidencialidad de los datos conforme a lo dispuesto en el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de los mismos.<\/p>\n\n\n\n<p>El usuario podr\u00e1 en cualquier momento ejercitar los derechos de acceso, oposici\u00f3n, rectificaci\u00f3n y cancelaci\u00f3n reconocidos en el citado Reglamento (UE). El ejercicio de estos derechos puede realizarlo el propio usuario a trav\u00e9s de email a: <a href=\"mailto:info@bikai.eu\">info@bikai.eu<\/a> o en la direcci\u00f3n: Alameda de Urkijo 4, 5\u00ba, 48008 Bilbao.<\/p>\n\n\n\n<p>El usuario manifiesta que todos los datos facilitados por \u00e9l son ciertos y correctos, y se compromete a mantenerlos actualizados, comunicando los cambios a Bikai S.L.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Finalidad del tratamiento de los datos personales:<\/strong><\/p>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 finalidad trataremos tus datos personales?<\/strong><\/p>\n\n\n\n<p>En Bikai S.L. trataremos tus datos personales recabados a trav\u00e9s del Sitio Web: bikai.eu, con las siguientes finalidades:<\/p>\n\n\n\n<p>1. En caso de contrataci\u00f3n de los bienes y servicios ofertados a trav\u00e9s de bikai.eu, para mantener la relaci\u00f3n contractual, as\u00ed como la gesti\u00f3n, administraci\u00f3n, informaci\u00f3n, prestaci\u00f3n y mejora del servicio.<\/p>\n\n\n\n<p>2. Env\u00edo de informaci\u00f3n solicitada a trav\u00e9s de los formularios dispuestos en bikai.eu<\/p>\n\n\n\n<p>3. Remitir boletines (newsletters), as\u00ed como comunicaciones comerciales de promociones y\/o publicidad de bikai.eu y del sector.<\/p>\n\n\n\n<p>Te recordamos que puedes oponerte al env\u00edo de comunicaciones comerciales por cualquier v\u00eda y en cualquier momento, remitiendo un correo electr\u00f3nico a la direcci\u00f3n indicada anteriormente.<\/p>\n\n\n\n<p>Los campos de dichos registros son de cumplimentaci\u00f3n obligatoria, siendo imposible realizar las finalidades expresadas si no se aportan esos datos.<\/p>\n\n\n\n<p><strong>\u00bfPor cu\u00e1nto tiempo se conservan los datos personales recabados?<\/strong><\/p>\n\n\n\n<p>Los datos personales proporcionados se conservar\u00e1n mientras se mantenga la relaci\u00f3n comercial o no solicites su supresi\u00f3n y durante el plazo por el cu\u00e1l pudieran derivarse responsabilidades legales por los servicios prestados.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Legitimaci\u00f3n:<\/strong><\/p>\n\n\n\n<p>El tratamiento de tus datos se realiza con las siguientes bases jur\u00eddicas que legitiman el mismo: 1. La solicitud de informaci\u00f3n y\/o la contrataci\u00f3n de los servicios de Bikai S.L., cuyos t\u00e9rminos y condiciones se pondr\u00e1n a tu disposici\u00f3n en todo caso, de forma previa a una eventual contrataci\u00f3n.<\/p>\n\n\n\n<p>2. El consentimiento libre, espec\u00edfico, informado e inequ\u00edvoco, en tanto que te informamos poniendo a tu disposici\u00f3n la presente pol\u00edtica de privacidad, que tras la lectura de la misma, en caso de estar conforme, puedes aceptar mediante una declaraci\u00f3n o una clara acci\u00f3n afirmativa, como el marcado de una casilla dispuesta al efecto.<\/p>\n\n\n\n<p>En caso de que no nos facilites tus datos o lo hagas de forma err\u00f3nea o incompleta, no podremos atender tu solicitud, resultando del todo imposible proporcionarte la informaci\u00f3n solicitada o llevar a cabo la contrataci\u00f3n de los servicios.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Destinatarios:<\/strong><\/p>\n\n\n\n<p>Los datos no se comunicar\u00e1n a ning\u00fan tercero ajeno a Bikai S.L., salvo obligaci\u00f3n legal.<\/p>\n\n\n\n<p>Como encargados de tratamiento, tenemos contratados a los siguientes proveedores de servicios, habi\u00e9ndose comprometido al cumplimiento de las disposiciones normativas, de aplicaci\u00f3n en materia de protecci\u00f3n de datos, en el momento de su contrataci\u00f3n:<\/p>\n\n\n\n<p>BIOK COMUNICACI\u00d3N ESTRAT\u00c9GICA SOCIEDAD LIMITADA, con domicilio en HUERTAS DE LA VILLA, 7-1\u00baA , BILBAO, 48007, NIF\/CIF B95754669, presta servicios de dise\u00f1o y gesti\u00f3n de la p\u00e1gina web bikai.eu.<\/p>\n\n\n\n<p>Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace: https:\/\/biokcomunicacion.com\/aviso-legal\/.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Datos recopilados por usuarios de los servicios<\/strong><\/p>\n\n\n\n<p>En los casos en que el usuario incluya ficheros con datos de car\u00e1cter personal en los servidores de alojamiento compartido, Bikai S.L. no se hace responsable del incumplimiento por parte del usuario del RGPD.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Retenci\u00f3n de datos en conformidad a la LSSI<\/strong><\/p>\n\n\n\n<p>Bikai S.L. informa de que, como prestador de servicio de alojamiento de datos y en virtud de lo establecido en la Ley 34\/2002 de 11 de julio de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI), retiene por un periodo m\u00e1ximo de 12 meses la informaci\u00f3n imprescindible para identificar el origen de los datos alojados y el momento en que se inici\u00f3 la prestaci\u00f3n del servicio. La retenci\u00f3n de estos datos no afecta al secreto de las comunicaciones y s\u00f3lo podr\u00e1n ser utilizados en el marco de una investigaci\u00f3n criminal o para la salvaguardia de la seguridad p\u00fablica, poni\u00e9ndose a disposici\u00f3n de los jueces y\/o tribunales o del Ministerio que as\u00ed los requiera.<\/p>\n\n\n\n<p>La comunicaci\u00f3n de datos a las Fuerzas y Cuerpos del Estado se har\u00e1 en virtud a lo dispuesto en la normativa sobre protecci\u00f3n de datos personales.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Derechos propiedad intelectual<\/strong><\/p>\n\n\n\n<p>Bikai S.L. es titular de todos los derechos de autor, propiedad intelectual, industrial, &#8220;know how&#8221; y cuantos otros derechos guardan relaci\u00f3n con los contenidos del sitio web bikai.eu y los servicios ofertados en el mismo, as\u00ed como de los programas necesarios para su implementaci\u00f3n y la informaci\u00f3n relacionada.<\/p>\n\n\n\n<p>No se permite la reproducci\u00f3n, publicaci\u00f3n y\/o uso no estrictamente privado de los contenidos, totales o parciales, del sitio web bikai.eu sin el consentimiento previo y por escrito.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Propiedad intelectual del software<\/strong><\/p>\n\n\n\n<p>El usuario debe respetar los programas de terceros puestos a su disposici\u00f3n por Bikai S.L., aun siendo gratuitos y\/o de disposici\u00f3n p\u00fablica.<\/p>\n\n\n\n<p>Bikai S.L. dispone de los derechos de explotaci\u00f3n y propiedad intelectual necesarios del software.<\/p>\n\n\n\n<p>El usuario no adquiere derecho alguno o licencia por el servicio contratado, sobre el software necesario para la prestaci\u00f3n del servicio, ni tampoco sobre la informaci\u00f3n t\u00e9cnica de seguimiento del servicio, excepci\u00f3n hecha de los derechos y licencias necesarios para el cumplimiento de los servicios contratados y \u00fanicamente durante la duraci\u00f3n de los mismos.<\/p>\n\n\n\n<p>Para toda actuaci\u00f3n que exceda del cumplimiento del contrato, el usuario necesitar\u00e1 autorizaci\u00f3n por escrito por parte de Bikai S.L., quedando prohibido al usuario acceder, modificar, visualizar la configuraci\u00f3n, estructura y ficheros de los servidores propiedad de Bikai S.L., asumiendo la responsabilidad civil y penal derivada de cualquier incidencia que se pudiera producir en los servidores y sistemas de seguridad como consecuencia directa de una actuaci\u00f3n negligente o maliciosa por su parte.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Propiedad intelectual de los contenidos alojados<\/strong><\/p>\n\n\n\n<p>Se proh\u00edbe el uso contrario a la legislaci\u00f3n sobre propiedad intelectual de los servicios prestados por Bikai S.L. y, en particular de:<\/p>\n\n\n\n<p>\u2022 La utilizaci\u00f3n que resulte contraria a las leyes espa\u00f1olas o que infrinja los derechos de terceros.<\/p>\n\n\n\n<p>\u2022 La publicaci\u00f3n o la transmisi\u00f3n de cualquier contenido que, a juicio de Bikai S.L., resulte violento, obsceno, abusivo, ilegal, racial, xen\u00f3fobo o difamatorio.<\/p>\n\n\n\n<p>\u2022 Los cracks, n\u00fameros de serie de programas o cualquier otro contenido que vulnere derechos de la propiedad intelectual de terceros.<\/p>\n\n\n\n<p>\u2022 La recogida y\/o utilizaci\u00f3n de datos personales de otros usuarios sin su consentimiento expreso o contraviniendo lo dispuesto en Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de los mismos.<\/p>\n\n\n\n<p>\u2022 La utilizaci\u00f3n del servidor de correo del dominio y de las direcciones de correo electr\u00f3nico para el env\u00edo de correo masivo no deseado.<\/p>\n\n\n\n<p>El usuario tiene toda la responsabilidad sobre el contenido de su web, la informaci\u00f3n transmitida y almacenada, los enlaces de hipertexto, las reivindicaciones de terceros y las acciones legales en referencia a propiedad intelectual, derechos de terceros y protecci\u00f3n de menores.<\/p>\n\n\n\n<p>El usuario es responsable respecto a las leyes y reglamentos en vigor y las reglas que tienen que ver con el funcionamiento del servicio online, comercio electr\u00f3nico, derechos de autor, mantenimiento del orden p\u00fablico, as\u00ed como principios universales de uso de Internet.<\/p>\n\n\n\n<p>El usuario indemnizar\u00e1 a Bikai S.L. por los gastos que generara la imputaci\u00f3n de Bikai S.L. en alguna causa cuya responsabilidad fuera atribuible al usuario, incluidos honorarios y gastos de defensa jur\u00eddica, incluso en el caso de una decisi\u00f3n judicial no definitiva.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Protecci\u00f3n de la informaci\u00f3n alojada<\/strong><\/p>\n\n\n\n<p>Bikai S.L. realiza copias de seguridad de los contenidos alojados en sus servidores, sin embargo no se responsabiliza de la p\u00e9rdida o el borrado accidental de los datos por parte de los usuarios. De igual manera, no garantiza la reposici\u00f3n total de los datos borrados por los usuarios, ya que los citados datos podr\u00edan haber sido suprimidos y\/o modificados durante el periodo del tiempo transcurrido desde la \u00faltima copia de seguridad.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Comunicaciones comerciales<\/strong><\/p>\n\n\n\n<p>En aplicaci\u00f3n de la LSSI. Bikai S.L. no enviar\u00e1 comunicaciones publicitarias o promocionales por correo electr\u00f3nico u otro medio de comunicaci\u00f3n electr\u00f3nica equivalente que previamente no hubieran sido solicitadas o expresamente autorizadas por los destinatarios de las mismas.<\/p>\n\n\n\n<p>En el caso de usuarios con los que exista una relaci\u00f3n contractual previa, Bikai S.L. s\u00ed est\u00e1 autorizado al env\u00edo de comunicaciones comerciales referentes a productos o servicios de Bikai S.L. que sean similares a los que inicialmente fueron objeto de contrataci\u00f3n con el cliente. En todo caso, el usuario, tras acreditar su identidad, podr\u00e1 solicitar que no se le haga llegar m\u00e1s informaci\u00f3n comercial a trav\u00e9s de los canales de Atenci\u00f3n al Cliente.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Protecci\u00f3n de datos de car\u00e1cter personal seg\u00fan la LOPD Bikai S.L., en aplicaci\u00f3n de la normativa vigente en materia de protecci\u00f3n de datos de car\u00e1cter personal, informa que los datos personales que se recogen a trav\u00e9s de los formularios del Sitio web: bikai.eu, se incluyen en los ficheros automatizados espec\u00edficos de usuarios de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5416","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy Policy - Bikai<\/title>\n<meta name=\"description\" content=\"P\u00e1gina web Pol\u00edtica de Privacidad de Bikai Participaciones Industriales.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Bikai\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina web Pol\u00edtica de Privacidad de Bikai Participaciones Industriales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Bikai\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-06T22:40:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/\",\"url\":\"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/\",\"name\":\"Privacy Policy - Bikai\",\"isPartOf\":{\"@id\":\"https:\/\/www.bikai.eu\/en\/#website\"},\"datePublished\":\"2023-01-19T09:00:00+00:00\",\"dateModified\":\"2023-02-06T22:40:29+00:00\",\"description\":\"P\u00e1gina web Pol\u00edtica de Privacidad de Bikai Participaciones Industriales.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.bikai.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bikai.eu\/en\/#website\",\"url\":\"https:\/\/www.bikai.eu\/en\/\",\"name\":\"Bikai Participaciones industriales\",\"description\":\"Bikai Participaciones Industriales\",\"publisher\":{\"@id\":\"https:\/\/www.bikai.eu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bikai.eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bikai.eu\/en\/#organization\",\"name\":\"Bikai Participaciones industriales\",\"url\":\"https:\/\/www.bikai.eu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bikai.eu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bikai.eu\/wp-content\/uploads\/2022\/11\/logo-bikai-pi-negro.png\",\"contentUrl\":\"https:\/\/www.bikai.eu\/wp-content\/uploads\/2022\/11\/logo-bikai-pi-negro.png\",\"width\":714,\"height\":430,\"caption\":\"Bikai Participaciones industriales\"},\"image\":{\"@id\":\"https:\/\/www.bikai.eu\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/bikai-participaciones-industriales\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Bikai","description":"P\u00e1gina web Pol\u00edtica de Privacidad de Bikai Participaciones Industriales.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - Bikai","og_description":"P\u00e1gina web Pol\u00edtica de Privacidad de Bikai Participaciones Industriales.","og_url":"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/","og_site_name":"Bikai","article_modified_time":"2023-02-06T22:40:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/","url":"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/","name":"Privacy Policy - Bikai","isPartOf":{"@id":"https:\/\/www.bikai.eu\/en\/#website"},"datePublished":"2023-01-19T09:00:00+00:00","dateModified":"2023-02-06T22:40:29+00:00","description":"P\u00e1gina web Pol\u00edtica de Privacidad de Bikai Participaciones Industriales.","breadcrumb":{"@id":"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bikai.eu\/en\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.bikai.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.bikai.eu\/en\/#website","url":"https:\/\/www.bikai.eu\/en\/","name":"Bikai Participaciones industriales","description":"Bikai Participaciones Industriales","publisher":{"@id":"https:\/\/www.bikai.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bikai.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bikai.eu\/en\/#organization","name":"Bikai Participaciones industriales","url":"https:\/\/www.bikai.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bikai.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.bikai.eu\/wp-content\/uploads\/2022\/11\/logo-bikai-pi-negro.png","contentUrl":"https:\/\/www.bikai.eu\/wp-content\/uploads\/2022\/11\/logo-bikai-pi-negro.png","width":714,"height":430,"caption":"Bikai Participaciones industriales"},"image":{"@id":"https:\/\/www.bikai.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bikai-participaciones-industriales\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/pages\/5416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/comments?post=5416"}],"version-history":[{"count":2,"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/pages\/5416\/revisions"}],"predecessor-version":[{"id":5433,"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/pages\/5416\/revisions\/5433"}],"wp:attachment":[{"href":"https:\/\/www.bikai.eu\/en\/wp-json\/wp\/v2\/media?parent=5416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}